{"id":771,"date":"2014-11-17T17:21:01","date_gmt":"2014-11-17T17:21:01","guid":{"rendered":"http:\/\/www.backlinktest.com\/blog\/?p=771"},"modified":"2019-03-04T16:54:27","modified_gmt":"2019-03-04T16:54:27","slug":"grundlagen-der-onpage-optimierung-teil-3-rich-snippets-verwenden","status":"publish","type":"post","link":"https:\/\/www.backlinktest.com\/blog\/grundlagen-der-onpage-optimierung-teil-3-rich-snippets-verwenden\/","title":{"rendered":"Grundlagen der OnPage-Optimierung, Teil 3: Rich Snippets verwenden"},"content":{"rendered":"<p>Sie sind Betreiber einer Website, deren Erstellung viel M\u00fche und Zeit gekostet hat. Auch in Suchmaschinenoptimierung wurde bereits investiert und endlich erscheint Ihre Seite auf der ersten Seite der Google-Suchergebnisse. Theoretisch sind die Klicks der User nicht mehr weit entfernt &#8230; <!--more--><\/p>\n<p>&#8230; doch die Seite steht im Wettbewerb mit vielen anderen Anbietern. Was k\u00f6nnen Sie also tun, um die User auf Ihre Seite zu bringen? Das Suchergebnis muss interessanter gestaltet werden, um sich so von der Suchergebnis-Konkurrenz abzuheben. Und genau das funktioniert mit so genannten \u201eRich Snippets\u201c.<\/p>\n<h2 class=\"tstyle\">Begriffsabgrenzung: Meta-Description und Rich Snippet<\/h2>\n<p>Wer bei Google nach etwas sucht, erh\u00e4lt &#8211; unter dem Titel des Suchergebnisses &#8211; einen kurzen Beschreibungstext. Hierbei handelt es sich um die so genannte \u201e<a href=\"https:\/\/www.backlinktest.com\/blog\/grundlagen-der-onpage-optimierung-teil-1\/\">Meta-Description<\/a>\u201c. Diese wird h\u00e4ndisch durch den Website-Betreiber im Backend verfasst. Wenn keine Meta-Description eingetragen wird, verwendet Google automatisch Textschnipsel rund um das vom User eingegebene Keyword, da Google diesen Stellen Relevanz zuspricht.<\/p>\n<p>Der Meta-Description kommt die wichtige Aufgabe zu, die Neugier des Users auf das Suchergebnis zu wecken und ihn zum Klicken zu animieren. Der von Google angezeigte Textausschnitt wird auch als \u201eSnippet\u201c, bezeichnet.<\/p>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.backlinktest.com\/blog\/wp-content\/uploads\/2014\/12\/google1.jpg\" alt=\"\" \/><br \/>\nQuelle: Google \u2013 Suchbegriff \u201eBotanischer Garten Mainz\u201c.<\/div>\n<p>Rich Snippets bieten &#8211; \u00fcber die regul\u00e4re Meta-Description hinaus &#8211; Informationen mit Semantik an, die dem Nutzer mehr Informationen als nur reinen Text bieten, zum Beispiel in Form einer Sterne- oder Google-Bewertung. Aber auch Videos, Daten, Preise und viele weitere Informationen sind an dieser Stelle m\u00f6glich, um dem Suchenden einen noch besseren Einblick in das Suchergebnis zu geben und relevante Informationen zu liefern.<\/p>\n<p>Enth\u00e4lt ein Suchergebnis Rich Snippets, ist es auch optisch deutlich auff\u00e4lliger als Suchergebnisse ohne angereicherte Daten.<\/p>\n<p>Das folgende Beispiel des Circus Krone zeigt die Erg\u00e4nzung des Snippets um eine Sterne- und Google-Bewertung.<\/p>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.backlinktest.com\/blog\/wp-content\/uploads\/2014\/12\/google2.jpg\" alt=\"\" \/><br \/>\nQuelle: Google \u2013 Suchbegriff \u201eCircus Krone\u201c.<\/div>\n<h2 class=\"tstyle\">Rich Snippets generieren<\/h2>\n<p>Damit Google die zus\u00e4tzlichen Informationen aus einer Seite herauslesen und Rich Snippets generieren kann, m\u00fcssen zun\u00e4chst die entsprechenden zus\u00e4tzlichen Tags im HTML-Code hinzugef\u00fcgt werden. HTML-Grundkenntnisse sind daher durchaus von Vorteil.<\/p>\n<p>Wer sich einen \u00dcberblick \u00fcber m\u00f6gliche Tags verschaffen m\u00f6chte, wird unter anderem bei <a href=\"https:\/\/www.schema.org\/docs\/gs.html\" target=\"_blank\" rel=\"noopener\">Schma.org<\/a> f\u00fcndig \u2013 ein gemeinsames Projekt von Yahoo, Microsoft und Google.<\/p>\n<p>Das Markup muss dann in einem der frei folgenden Formate implementiert werden, um Rich Snippets auf der Website verwenden zu k\u00f6nnen:<\/p>\n<ul>\n<li>Mikrodaten<\/li>\n<li> Mikroformate<\/li>\n<li> RDFa<\/li>\n<\/ul>\n<h2 class=\"tstyle\">Beispiel f\u00fcr die Implementierung von Mikrodaten<\/h2>\n<p>Sie haben eine Website f\u00fcr eine Folklore-Tanzgruppe erstellt. Das Rich Snippet soll nun das Datum des n\u00e4chsten Auftritts anzeigen. Hierf\u00fcr muss das Datum im Rahmen der HTML-Programmierung in ein so genanntes \u201eTime-Tag\u201c eingebettet werden. Google kann so erkennen, dass die Meta-Description um weitere relevante Daten, n\u00e4mlich das Datum, erg\u00e4nzt wurde und erzeugt so das entsprechende Rich-Snippet. <\/p>\n<p>Der HTML-Code f\u00fcr diese Mikrodaten k\u00f6nnte dann folgenderma\u00dfen aussehen:<\/p>\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.backlinktest.com\/blog\/wp-content\/uploads\/2014\/12\/quelltext.jpg\" \/><\/div>\n<p>Mikrodaten eignen sich besonders gut zur Auszeichnung von Website-Inhalten, denn sie stellen einfache Attribute in HTML-Tags dar.<\/p>\n<p>Google unterst\u00fctzt unter anderem die Deklarierung folgender Inhaltstypen im Quellcode:<\/p>\n<ul>\n<li>Videos<\/li>\n<li> Musik<\/li>\n<li> Veranstaltungen<\/li>\n<li> Rezepte<\/li>\n<li> Unternehmen<\/li>\n<li> Organisationen<\/li>\n<li> Produkte<\/li>\n<li> Personen<\/li>\n<li> Erfahrungsberichte<\/li>\n<\/ul>\n<p>Im letzten Schritt wird schlie\u00dflich getestet, ob Google die auf der Website ausgezeichneten Inhalte erkennen kann. Hierf\u00fcr stellt der Suchmaschinenanbieter ein entsprechendes Tool zur Verf\u00fcgung, das \u201e<a href=\"https:\/\/search.google.com\/structured-data\/testing-tool\" target=\"_blank\" rel=\"noopener\">Test-Tool f\u00fcr strukturierte Daten<\/a>\u201c. Geben Sie die entsprechende URL zur \u00dcberpr\u00fcfung ein und mit einem Klick auf \u201eVorschau\u201c werden das Rich Snippet sowie weitere von der Seite extrahierte Daten angezeigt.<\/p>\n<h2 class=\"tstyle\">Fazit<\/h2>\n<p>Die Daten-Strukturierung beeinflusst bislang nicht das Google-Ranking \u2013 im Hinblick von k\u00fcnftigen Algorithmus-\u00c4nderungen ist es jedoch strategisch sinnvoll, die Suchergebnisse anzureichern.<br \/>\nAuf diese Weise kommt die Suchmaschine besser mit den Daten zurecht. Sind Rich Snippets entsprechend formuliert und enthalten sie die Informationen, die der User sucht, steigt auch die Wahrscheinlichkeit auf einen h\u00f6heren Website-Traffic. <\/p>\n<h2 class=\"tstyle\">Weiterf\u00fchrendes<\/h2>\n<p>&raquo; <a href=\"https:\/\/www.backlinktest.com\/blog\/grundlagen-der-onpage-optimierung-teil-1\/\">zum ersten Teil des Onpage-Optimierung Hintergrundberichtes<\/a><br \/>\n&raquo; <a href=\"https:\/\/www.backlinktest.com\/blog\/grundlagen-der-onpage-optimierung-teil-2-meta-robots-tag\"> zum zweiten Teil des Onpage-Optimierung Hintergrundberichtes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie sind Betreiber einer Website, deren Erstellung viel M\u00fche und Zeit gekostet hat. Auch in Suchmaschinenoptimierung wurde bereits investiert und endlich erscheint Ihre Seite auf &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[200],"tags":[],"class_list":["post-771","post","type-post","status-publish","format-standard","hentry","category-seo-tipps"],"aioseo_notices":[],"views":3541,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1Rh7p-cr","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":0,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts\/771\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/categories?post=771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/tags?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}