{"id":680,"date":"2014-08-06T15:18:04","date_gmt":"2014-08-06T15:18:04","guid":{"rendered":"http:\/\/www.backlinktest.com\/blog\/?p=680"},"modified":"2018-11-06T09:00:54","modified_gmt":"2018-11-06T09:00:54","slug":"die-neuen-top-level-domains-auswirkungen-auf-das-seo","status":"publish","type":"post","link":"https:\/\/www.backlinktest.com\/blog\/die-neuen-top-level-domains-auswirkungen-auf-das-seo\/","title":{"rendered":"Die neuen Top-Level-Domains: Auswirkungen auf das SEO?"},"content":{"rendered":"<p>Eine Domain ist ein weltweit geltender, einmaliger, eindeutiger und \u2013 im Rahmen gewisser Richtlinien \u2013 frei w\u00e4hlbarer Name einer Internetseite. Der Begriff \u201eTop-Level-Domain\u201c bezeichnet die Endung des Domainnamens.<!--more--><\/p>\n<p>Insgesamt wird zwischen vier Arten von Top-Level-Domains unterschieden:<\/p>\n<ul>\n<li>Gesponserte Domains (sTLD),<\/li>\n<li>Nichtgesponserte Domains (uTLD),<\/li>\n<li>L\u00e4nderspezifische Top-Level-Domains (ccTLD),<\/li>\n<li>Die neuen Top-Level-Domains (gTLD).<\/li>\n<\/ul>\n<p>Hinzu kommen einige Sonderf\u00e4lle und Ausnahmen, die jedoch im Folgenden nicht Gegenstand des Artikels sind.<\/p>\n<h2 class=\"tstyle\">Gesponserte Domains<\/h2>\n<p>Gesponserte Domains, kurz sTLDs, unterstehen der Kontrolle von unabh\u00e4ngigen Organisationen, welche die Vergaberichtlinien definieren. So legte beispielsweise das US-Milit\u00e4r fest, dass \u201e.mil\u201c nur durch das US-amerikanische Milit\u00e4r genutzt werden darf, \u201e.gov\u201c steht f\u00fcr die Regierungsstellen der USA, \u201e.edu\u201c f\u00fcr Bildungseinrichtungen. sTLDs k\u00f6nnen bei der Internet Corporation for Assigned Names and Numbers, kurz ICANN, von weltweit operierenden Organisationen und Unternehmen beantragt werden.<\/p>\n<h2 class=\"tstyle\">Nichtgesponserte Domains<\/h2>\n<p>Nichtgesponserte Top-Level-Domains (uTLDs) unterliegen der direkten Kontrolle der Internet Society und der ICANN. Diese Domains bestehen aus mindestens drei oder mehr Zeichen und stehen f\u00fcr eine bestimmte Gruppe. So steht beispielsweise \u201e.pro\u201c f\u00fcr zertifizierte Fachkr\u00e4fte. Die Domain\u201e.info\u201c steht f\u00fcr Informationsanbieter, ist aber grunds\u00e4tzlich frei zug\u00e4nglich \u2013 genau wie \u201e.com\u201c (stand urspr\u00fcnglich f\u00fcr Unternehmen) oder \u201e.org\u201c (urspr\u00fcnglich f\u00fcr Non-Profit-Organisationen gedacht).<\/p>\n<h2 class=\"tstyle\">L\u00e4nderspezifische Domains<\/h2>\n<p>Allgemeine K\u00fcrzel wir .biz, .com, .net, etc. wurden bislang von rund 250 L\u00e4nderendungen erg\u00e4nzt. So steht beispielsweise \u201e.de\u201c f\u00fcr Deutschland oder \u201e.fr\u201c f\u00fcr Frankreich. Anfang des vergangenen Jahres startete die ICANN dann die Einf\u00fchrung von rund 1.400 neuen Top-Level-Domains, den so genannten \u201egTLDs\u201c.<\/p>\n<h2 class=\"tstyle\">Die neuen Top-Level-Domains<\/h2>\n<p>Der Grund f\u00fcr die Neueinf\u00fchrung der Top-Level-Domains ist, dass es in der Vergangenheit immer schwieriger wurde, pr\u00e4gnante Adressen unter den bestehenden Endungen zu finden &#8211; viele Zeichenketten auf der zweiten Ebene waren bereits vergeben. Um den Adressraum zu erweitern und mehr Domains zuzulassen, wurden die neuen Top-Level-Domains ins Leben gerufen.<\/p>\n<h2 class=\"tstyle\">Der Vergabeprozess<\/h2>\n<p>Organisationen und Unternehmen k\u00f6nnen sich seit M\u00e4rz 2013 bei der ICANN als Betreiber f\u00fcr eine eigene Domain-Endungen bewerben. Diese M\u00f6glichkeit nehmen vor allem gro\u00dfe Konzerne wie Apple, BMW oder Audi in Anspruch, um die Top-Level-Domain f\u00fcr die eigene IT-Infrastruktur zu nutzen.<br \/>\nZur Verf\u00fcgung stehen auch so genannte \u201eOffene Top-Level-Domains\u201c. Diese sind dadurch gekennzeichnet, dass sie grunds\u00e4tzlich jedermann f\u00fcr die Registrierung zur Verf\u00fcgung stehen. Hierunter fallen neue Domain-Endungen, wie beispielsweise \u201e.blog\u201c oder \u201e.hotel\u201c.<\/p>\n<p>Eine dritte Gruppe bilden geografische Top-Level-Domains, die sich auf eine Stadt oder eine Region beziehen. Domain-Endungen wie \u201e.m\u00fcnchen\u201c oder \u201e.leipzig\u201c d\u00fcrfen jedoch nur dann registriert werden, wenn ein \u00f6rtlicher Bezug des Registrierenden \u2013 unabh\u00e4ngig davon ob es sich um ein Unternehmen oder eine Privatperson handelt \u2013 nachweisbar vorhanden ist.<\/p>\n<p>Nat\u00fcrlich stellt sich im Zuge der Neuerungen die Frage, ob sich die Domain-Endungen k\u00fcnftig auf das SEO auswirken.<\/p>\n<h2 class=\"tstyle\">Auswirkungen auf das SEO<\/h2>\n<p>Ob sich die neuen Domain-Endungen k\u00fcnftig auf das Suchmaschinen-Ranking auswirken, wird bereits vielfach diskutiert. Die Ger\u00fcchte wurden vor allem dadurch angeheizt, dass sich Google f\u00fcr rund 100 Top-Level-Domains beworben hat. Wie jedoch der Konzern best\u00e4tigte, haben die neuen Endungen zurzeit keine Auswirkungen auf das Ranking. <\/p>\n<p>Dennoch ist nicht auszuschlie\u00dfen, dass diese nicht langfristig doch als Ranking-Faktor gelten werden, denn die \u201eklassische\u201c Top-Level-Domain ist bereits einer von 200 Google-Rankingfaktoren. Sobald Websites mit den neuen Domain-Endungen zuverl\u00e4ssige Relevanz-Signale liefern, ist es wahrscheinlich, dass diese ebenfalls in den Algorithmus von Google einflie\u00dfen. <\/p>\n<p>So k\u00f6nnte beispielsweise &#8211; sofern Google die geografische Domain-Endung als Ranking-Faktor ber\u00fccksichtigt &#8211; ein Schneider aus M\u00fcnchen unter \u201eschneider.m\u00fcnchen\u201c gefunden werden und sich damit besser positionieren, als mit einer generischen Domain-Endung.<br \/>\nSo w\u00e4re auch denkbar, dass Google k\u00fcnftig geografische Domains besser rankt, wenn die lokale Suche genutzt wird. Diese Vermutung wird durch die Tatsache best\u00e4rkt, dass bei der Bewerbung um eine geografische Domain auch der Unternehmens- bzw. Wohnsitz angegeben werden muss.<\/p>\n<h2 class=\"tstyle\">Vor- und Nachteile f\u00fcr Website-Betreiber<\/h2>\n<p>Positiv ist, dass es nun weitaus einfacher wird, eine passende Domain-Endung zu finden. Die neue Bandbreite an Top-Level-Domains kommt vor allem Start-Ups entgegen, die in der Vergangenheit h\u00e4ufig zwischen unbrauchbaren \u201eDomain-\u00dcberbleibseln\u201c w\u00e4hlen mussten, da keine passenden pr\u00e4gnanten Domains mehr zur Verf\u00fcgung standen. <\/p>\n<p>Auch f\u00fcr Privatpersonen besteht nat\u00fcrlich die M\u00f6glichkeit, eine passende Domain zu erhalten.<br \/>\nDoch wo Licht ist, f\u00e4llt auch Schatten. So sehen viele Betreiber den Schutz des eigenen Namens in Gefahr, denn mit den neuen Domain-Endungen steigt auch die Wahrscheinlichkeit von Urheberrechtsverst\u00f6\u00dfen, welche aus dem unberechtigten Registrieren von Domainnamen resultieren k\u00f6nnten. So empfiehlt es sich f\u00fcr bekannte Marken einen Eintrag in das Trademark Clearinghouse durchzuf\u00fchren. <\/p>\n<p>Das Trademark Clearinghouse wurde im Zuge der Einf\u00fchrung der neuen Top-Level-Domains geschaffen, um Inhaber eingetragener Marken vor Missbrauch zu sch\u00fctzen. Dieses kann nur f\u00fcr solche Marken in Anspruch genommen werden, die im Markenregister vermerkt sind und best\u00e4tigt wurden.<\/p>\n<p>Das Trademark Clearinghouse umfasst zwei Mechanismen:<\/p>\n<ul>\n<li>Der so genannte \u201eSunrise Service\u201c gew\u00e4hrleistet, dass Inhaber einer Marke vor verbindlicher Einf\u00fchrung der neuen Domains diejenigen registrieren k\u00f6nnen, welche die Marke beinhalten oder sich eindeutig auf diese beziehen. <\/li>\n<li>Im Rahmen des Trademark Claims Service erhalten Markeninhaber eine Benachrichtigung, wenn jemand unerlaubterweise versucht, die Domain-Endung einer eingetragenen Marke zu registrieren. <\/li>\n<\/ul>\n<h2 class=\"tstyle\">Domain-Endung vorbestellen<\/h2>\n<p>Wer sich eine der neuen Domain-Endungen sichern m\u00f6chte, kann sich noch bis Anfang 2016 hierf\u00fcr registrieren. Die Vorbestellungen sind kostenlos und zudem auch unverbindlich, da die Zeitpunkte f\u00fcr die Einf\u00fchrung der jeweiligen Domains teilweise noch nicht feststehen. Die unverbindliche Domain-Reservierung sorgt daf\u00fcr, dass kein anderer die gew\u00fcnschte Endung reservieren kann, bis die Vorbestellung verbindlich gemacht wird \u2013 sofern die gew\u00fcnschte Domain-Endung zugelassen wird.<\/p>\n<p>Vermutlich bewegen sich die j\u00e4hrlichen Geb\u00fchren in einem Rahmen zwischen 20 und 100 Euro, die genauen Entgelte werden jedoch noch festgelegt.<\/p>\n<h2 class=\"tstyle\">Fazit<\/h2>\n<p>Nicht nur Rechtsabteilungen von Unternehmen m\u00fcssen sich k\u00fcnftig wohl mit den neuen Domain-Endungen auseinandersetzen, sondern auch Marketing-Agenturen und \u2013 Abteilungen, um das Potenzial f\u00fcr die Kommunikation zu eruieren und in der Zukunft optimal zu nutzen. Fakt ist auch: Viele User werden sich an die neuen Endungen erst einmal gew\u00f6hnen m\u00fcssen. <\/p>\n<p>Wann und inwieweit sich die neuen Endungen auf das SEO auswirken, bleibt zun\u00e4chst einmal abzuwarten. Grunds\u00e4tzlich gilt aber: Der Bereich SEO ist sehr schnelllebig und in der Vergangenheit hat sich gezeigt, dass vor allem derjenige profitiert, der langfristig denkt und am Ball bleibt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Domain ist ein weltweit geltender, einmaliger, eindeutiger und \u2013 im Rahmen gewisser Richtlinien \u2013 frei w\u00e4hlbarer Name einer Internetseite. Der Begriff \u201eTop-Level-Domain\u201c bezeichnet die &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[200],"tags":[46,47,39,43],"class_list":["post-680","post","type-post","status-publish","format-standard","hentry","category-seo-tipps","tag-domain","tag-endung","tag-neu","tag-seo"],"aioseo_notices":[],"views":14685,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1Rh7p-aY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":0,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/posts\/680\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/categories?post=680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.backlinktest.com\/blog\/wp-json\/wp\/v2\/tags?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}